{"id":11070,"date":"2015-08-11T04:19:58","date_gmt":"2015-08-11T02:19:58","guid":{"rendered":"http:\/\/www.vom-taubertal.de\/blog\/?p=11070"},"modified":"2017-01-05T10:21:49","modified_gmt":"2017-01-05T08:21:49","slug":"hilfe-wir-sind-sachen-oder-etwa-doch-nicht","status":"publish","type":"post","link":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/","title":{"rendered":"Hilfe, wir sind Sachen \u2013 oder etwa doch nicht?"},"content":{"rendered":"<p>Vielfach wird in diversen Foren oder Gruppen behauptet, das Tiere nur einfach eine Sache sind. Das dem aber nicht ganz so stimmt, erkl\u00e4rt euch unsere heutige Gastautorin, Daniela Molnar in diesem Beitrag<strong>.<br \/>\n<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Wie oft hat man schon den Satz geh\u00f6rt: \u201eKatzen und Hunde sind ja laut Gesetz nur Sachen.\u201c Viele denken sich dabei Unversch\u00e4mtheit, oder es zeige die mangelnde Wertsch\u00e4tzung des Gesetzgebers.<\/p>\n<p>Doch diese Annahmen beruhen lediglich darauf, dass man die Hintergr\u00fcnde des Gesetzgebers weder kennt noch nachvollziehen kann.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-11072\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?resize=300%2C200&#038;quality=100&#038;ssl=1\" alt=\"Katzen_Sache_02\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?w=800&amp;quality=100&amp;ssl=1 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Wir wollen doch mal sehen, ob wir diese Aussage n\u00e4her betrachten k\u00f6nnen, denn wie in der Jurisprudenz sind Pauschalaussagen wie immer sehr schwierig. Seit bereits einigen Jahren hat der Gesetzgeber den Tierschutz als Staatszielbestimmung in das GG geschrieben. Das l\u00e4sst sich in Art. 20 a nachlesen. Damit verpflichtet sich der Gesetzgeber dem Tierschutz und diesem im Rahmen seiner M\u00f6glichkeiten gerecht zu werden. In Deutschland gibt es ein sehr umfangreiches Tierschutzgesetz.<\/p>\n<p>Unser BGB und die entsprechenden Paragraphen sind aber weitaus \u00e4lter als die Staatszielbestimmung. Der Paragraph 90a BGB ist in der derzeitigen Fassung seitdem 2.1.2002 im BGB verankert.<\/p>\n<p>Er lautet:<\/p>\n<p><strong>\u201eTiere sind keine Sachen. Sie werden durch besondere Gesetze gesch\u00fctzt. Auf sie sind die f\u00fcr Sachen geltenden Vorschriften entsprechend anzuwenden, soweit nicht etwas anderes bestimmt ist.\u201c<\/strong><\/p>\n<p>Eine h\u00e4ufige Kritik ist aus Tierschutzkreisen zu vernehmen, dass diese Regelung inhaltsleer sei, da sie nicht hinreichend bestimmt sei.<\/p>\n<p>Diese Formulierung ist ein Kunstgriff, es erlaubt es dem Anspruchssteller <strong>Anspr\u00fcche im Zivilrecht geltend zu machen<\/strong>. Denn Tiere m\u00fcssen bei Zivilrechtlichen Verfahren auch ber\u00fccksichtigt werden. Im Falle einer Scheidung, sind Haustiere sogar als Hausrat anzusehen.<\/p>\n<p>Man ben\u00f6tigt also eine Anspruchsgrundlage, bei Schadensersatz wird <strong>auch im Zivilrecht zwischen Sachen und Tieren unterschieden. <\/strong>Gerade dann wenn ein Tier durch eine andere Person verletzt worden ist, das ist normiert in \u00a7251 BGB. Eine rein wirtschaftliche Betrachtung ist also nicht angemessen. Es findet durch das Gericht eine Abw\u00e4gung statt, ob die Heilkosten und die M\u00f6glichkeit das Tier noch zu retten, in einem sinnvollen Zueinander stehen.<\/p>\n<p>Das Landgericht Bielefeld, hat eine Heilbehandlung in H\u00f6he von 1500 Euro bei einer Hauskatze, als vertretbar angesehen.<\/p>\n<h3>Wie ist es im Strafrecht?<\/h3>\n<p>Es ist fraglich ob man den Sachbegriff hier so einfach \u00fcbertragen kann. Historisch gesehen ist das StGB deutlich \u00e4lter, es wurde 1871 verabschiedet und hat seitdem viele umfassende Reformen erlebt.<\/p>\n<p>Das BGB selbst wurde erst um 1900 herum verabschiedet. In diesen 30 Jahren gab es bereits eine immense Entwicklung in der Jurisprudenz.<\/p>\n<p>Wenn man die Regelungen des \u00a7 90 und 90 a BGB n\u00e4her betrachtet, so wird man zwei Dinge feststellen:<\/p>\n<ol>\n<li>\u00a7 90 a BGB konkretisiert lediglich den \u00a7 90 BGB<\/li>\n<li>Werden nur Sachen \u201eim Sinne DIESES Gesetzes\u201c definiert. Damit ist nur das BGB gemeint.<\/li>\n<\/ol>\n<p>Das Strafrecht selbst schreibt Tieren in den \u00a7\u00a7 324 a I Nr. 1, 325 IV Nr.1 StGB eine Sachqualit\u00e4t zu.<\/p>\n<p>Abschlie\u00dfend sei noch erg\u00e4nzt das Tiere nicht mehr Pf\u00e4ndbar sind, solange sie nicht zu Erwerbszecken gehalten werden.<\/p>\n<p><script type=\"text\/javascript\">\/\/ <![CDATA[ google_ad_client = \"ca-pub-3363977028533397\"; google_ad_slot = \"3531969263\"; google_ad_width = 468; google_ad_height = 60; \/\/ ]]><\/script><br \/>\n<!-- gro\u00dfer Banner --><br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\" type=\"text\/javascript\">\/\/ <![CDATA[ \/\/ ]]><\/script><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 253px; left: 20px;\">Merken<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 244px; left: 20px;\">Merken<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vielfach wird in diversen Foren oder Gruppen behauptet, das Tiere nur einfach eine Sache sind. Das dem aber nicht ganz<\/p>\n","protected":false},"author":1,"featured_media":11072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1,466],"tags":[814,816,21,815,383],"class_list":["post-11070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-katzen-perserkatzen-taubertalperser","category-haltung-perserkatzen-katzen-taubertalperser","tag-bgb","tag-gesetze","tag-katzen","tag-stgb","tag-tierschutz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser<\/title>\n<meta name=\"description\" content=\"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser\" \/>\n<meta property=\"og:description\" content=\"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Taubertalperser\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-11T02:19:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-05T08:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afrank\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afrank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/\"},\"author\":{\"name\":\"afrank\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"headline\":\"Hilfe, wir sind Sachen \u2013 oder etwa doch nicht?\",\"datePublished\":\"2015-08-11T02:19:58+00:00\",\"dateModified\":\"2017-01-05T08:21:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1\",\"keywords\":[\"BGB\",\"Gesetze\",\"Katzen\",\"StgB\",\"Tierschutz\"],\"articleSection\":{\"1\":\"Haltung\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/\",\"name\":\"Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1\",\"datePublished\":\"2015-08-11T02:19:58+00:00\",\"dateModified\":\"2017-01-05T08:21:49+00:00\",\"description\":\"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hilfe, wir sind Sachen \u2013 oder etwa doch nicht?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\",\"name\":\"Die Taubertalperser\",\"description\":\"Alles \u00fcber und f\u00fcr Katzen \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\",\"name\":\"afrank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"width\":653,\"height\":800,\"caption\":\"afrank\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser","description":"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/","og_locale":"de_DE","og_type":"article","og_title":"Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser","og_description":"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar","og_url":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/","og_site_name":"Die Taubertalperser","article_published_time":"2015-08-11T02:19:58+00:00","article_modified_time":"2017-01-05T08:21:49+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg","type":"image\/jpeg"}],"author":"afrank","twitter_misc":{"Verfasst von":"afrank","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#article","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/"},"author":{"name":"afrank","@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"headline":"Hilfe, wir sind Sachen \u2013 oder etwa doch nicht?","datePublished":"2015-08-11T02:19:58+00:00","dateModified":"2017-01-05T08:21:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1","keywords":["BGB","Gesetze","Katzen","StgB","Tierschutz"],"articleSection":{"1":"Haltung"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/","url":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/","name":"Hilfe - wir sind Sachen oder etwa doch nicht? - Taubertalperser","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#primaryimage"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1","datePublished":"2015-08-11T02:19:58+00:00","dateModified":"2017-01-05T08:21:49+00:00","description":"Hilfe wir sind Sachen oder etwa doch nicht. Dieser \u00e4u\u00dferst interessanten Frage beantwortet heute unsere Gastautorin Daniela Molnar","breadcrumb":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.vom-taubertal.de\/blog\/hilfe-wir-sind-sachen-oder-etwa-doch-nicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vom-taubertal.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Hilfe, wir sind Sachen \u2013 oder etwa doch nicht?"}]},{"@type":"WebSite","@id":"https:\/\/www.vom-taubertal.de\/blog\/#website","url":"https:\/\/www.vom-taubertal.de\/blog\/","name":"Die Taubertalperser","description":"Alles \u00fcber und f\u00fcr Katzen ","publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vom-taubertal.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049","name":"afrank","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","contentUrl":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","width":653,"height":800,"caption":"afrank"},"logo":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2015\/07\/Katzen_Sache_02.jpg?fit=800%2C533&quality=100&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/11070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/comments?post=11070"}],"version-history":[{"count":6,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/11070\/revisions"}],"predecessor-version":[{"id":17482,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/11070\/revisions\/17482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media\/11072"}],"wp:attachment":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media?parent=11070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/categories?post=11070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/tags?post=11070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}