{"id":22600,"date":"2018-04-22T10:00:39","date_gmt":"2018-04-22T08:00:39","guid":{"rendered":"http:\/\/www.vom-taubertal.de\/blog\/?p=22600"},"modified":"2025-01-29T18:55:34","modified_gmt":"2025-01-29T16:55:34","slug":"shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser","status":"publish","type":"post","link":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/","title":{"rendered":"M\u00e4rkte und Heimtiere in Shanghai \u2013 Taubertalperser"},"content":{"rendered":"<p>Ihr habt schon das eine oder andere von meiner Shanghai-Reise lesen d\u00fcrfen und heute entf\u00fchr ich euch hier zu diversen M\u00e4rkten&nbsp;die es zu Hauf in Shanghai gibt.<\/p>\n<p>Und f\u00fcr uns Westeurop\u00e4er doch eine interessante Erfahrung. Beginnen m\u00f6chte ich mit dem Fake-Mark unweit der Zhonghua Rd.<\/p>\n<p><!--more--><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22601 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Fakemarkt.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Fakemarket\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Fakemarkt.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Fakemarkt.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Fakemarkt.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>In diesen Markt stolperte ich rein zuf\u00e4lligerweise und es war gar nicht so geplant gewesen, er ist sicher kein besonders sch\u00f6ner und toller Markt, ich bin sogar eher davon \u00fcberzeugt, dass es hier weitaus bessere gibt.<\/p>\n<p>Aber einkaufen ist hier egal auf welchen Fake-Markt ein Risikospiel. Bei manchen erkennt man es auf den ersten Blick, das es sich hier um kein Originalprodukt handelt, bei anderen eher erst auf den 2. Blick aber selbst wenn uns dies egal ist bleibt die bange Frage \u201eBekomm ich dies durch den Zoll?\u201c<\/p>\n<p>Hier in diesem Market \u00fcberwog die Techniksparte und so konnte man hier alles kaufen angefangen von Wasserkocher bis hin zum ausgekl\u00fcgelten Karaoke-System.<\/p>\n<p>Aufgefallen, dass es ein Fake-Market war, ist es mir anhand eines Hello Kitty-Weckers, den ich mir unter normalen Umst\u00e4nden vielleicht gekauft h\u00e4tte aber anhand des Schriftzuges war f\u00fcr mich die F\u00e4lschung schon augenscheinlich.<\/p>\n<p>F\u00fcr mich sind solche M\u00e4rkte aber ehrlicherweise absolut nichts. Und so habe ich diesen Markt recht schnell wieder verlassen um bei strahlendem Sonnenschein weiter an kleinen chinesischen L\u00e4den entlangzulaufen.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#Lebensmittelmaerkte_und_Imbiss_in_Shanghai\" >Lebensmittelm\u00e4rkte und Imbiss in Shanghai<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#Der_Markt_fuer_Planzen_und_Heimtiere_in_Shanghai\" >Der Markt f\u00fcr Planzen und Heimtiere in Shanghai<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#Heimtiere_und_ihre_Haltung_in_Shanghai\" >Heimtiere und ihre Haltung in Shanghai<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Lebensmittelmaerkte_und_Imbiss_in_Shanghai\"><\/span>Lebensmittelm\u00e4rkte und Imbiss in Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22602 alignright\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-04.jpg?resize=200%2C300&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Essen, Taubertalperser, Reisen\" width=\"200\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-04.jpg?resize=200%2C300&amp;quality=100&amp;ssl=1 200w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-04.jpg?w=533&amp;quality=100&amp;ssl=1 533w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Diese waren weitaus interessanter und es reihte sich neben zahlreichen Lebensmittell\u00e4den auch der eine oder andere Imbissverk\u00e4ufer ein. Und ein gutes Indiz f\u00fcr leckeres Essen sind immer entsprechende Menschenmassen die davor angestellt sind.<\/p>\n<p>Fast \u00fcberall in Shanghai stolpert man auch \u00fcber diese Tea-Soja-Eier, Dumplings oder auch Buns. Aber auch Fleischspie\u00dfe mit Oktopus (und die waren super frisch), H\u00fchnchen usw. bekommt man oft zu kaufen.<\/p>\n<p>Sehr begehrt sind in Shanghai auch Joghurt to go und diverse Fruchts\u00e4fte.<\/p>\n<p>Der Hygienezustand mancher Imbissbuden war nun nicht so wirklich berauschend und so habe ich bei dem einen oder anderen doch meine Experimentierfreude au\u00dfen vor gelassen und lieber nur fotografiert J<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22603 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-01.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Lebensmittelmarkt\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-01.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-01.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Lebensmittelmarkt-Taubertalperser-01.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Faszinierend fand ich auch die Markthallte mit all ihren H\u00e4ndlern und super frischen Produkten. Okay, der WKD h\u00e4tte hier auch den absoluten Horror bekommen aber es sah alles sehr appetitlich und ansprechend aus und das Fleisch \u2026.. nun seht selber auf den Fotos, abgesehen davon das es hier keine K\u00fchlung gab \u2013 die optische Qualit\u00e4t war echt 1A.<\/p>\n<p>Kennt ihr in den diversen M\u00e4rkten die \u201eMarktschreier\u201c die versuchen ihren Gem\u00fcsehobel an den Mann respektive Frau zu bekommen?<\/p>\n<p>Die gibt\u2019s auch in Shanghai und ich empfand es als \u00fcberaus am\u00fcsant dies ganze mir mal in einer anderen Sprache anzusehen.<\/p>\n<p>Abends gibt es \u00fcbrigens in einer Seitenstra\u00dfe der Nijang Lu eine \u201eFress-Meile\u201c und es roch teilweise fantastisch und auch das Brot direkt beim Feuer gebacken \u2013 sehr, sehr genial.<\/p>\n<p>Aber kommen wir doch zu dem Thema, dass mich und vor allem euch wohl am meisten interessieren wird.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Der_Markt_fuer_Planzen_und_Heimtiere_in_Shanghai\"><\/span>Der Markt f\u00fcr Planzen und Heimtiere in Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22606 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-16.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Blumenmarkt\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-16.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-16.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-16.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Etwas, was ich unbedingt sehen wollte war einer dieser Pflanzen- und Heimtierm\u00e4rkte in Shanghai. Klar als Tierliebhaberin interessiert mich dies nat\u00fcrlich brennend.<br \/>\nIch lies mich mit dem Taxi zur Jiang Yin Lu&nbsp; \/ Xizang Lu bringen und schon sah ich die ersten Blumenl\u00e4den. Also Blumenbinden, sch\u00f6ne Blumengestecke machen k\u00f6nnen sie in Shanghai eindeutig.<\/p>\n<p>Unscheinbar zwischen zwei H\u00e4usern hindurch ging es dann in das Innere dieses Marktes \u2013 kleine verwinkelte Wege f\u00fchrten an noch viel kleineren L\u00e4den vorbei und teilweise unterschieden sie sich, abgesehen von der Gr\u00f6\u00dfe und Sauberkeit, nicht viel von unseren europ\u00e4ischen M\u00e4rkten.<\/p>\n<p>Wenn, ja, wenn da nicht das Tierangebot gewesen w\u00e4re.<\/p>\n<p>Hier musste man als Tierfreund doch ganz sch\u00f6n mit sich k\u00e4mpfen \u2013 w\u00e4hrend wir in Deutschland darum k\u00e4mpfen Tiere nicht fr\u00fchzeitig von ihren M\u00fcttern zu trennen, den Verkauf generell Gro\u00dfteils in den L\u00e4den verbieten wollen werden dort noch in winzigen Behausungen Streifenh\u00f6rnchen, M\u00e4use, Hamster etc. angeboten.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22607 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-08.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Tiermarkt\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-08.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-08.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiermarkt-08.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Aber auch in den Verkaufsaquarien war ein extremer \u00dcberbesatz zu erkennen. Gl\u00fccklich waren da wohl nur die Verk\u00e4ufer wenn sie wieder Umsatz gemacht hatten.<\/p>\n<p>Ganz furchtbar waren f\u00fcr mich anzusehen die K\u00e4fige mit den Hunde- und Katzenwelpen. Teilweise noch keine 6 Wochen alt waren sie in einem K\u00e4fig ohne R\u00fcckzugs- und Kuschelm\u00f6glichkeit. Der Gitterboden war sicherlich nicht so f\u00f6rderlich f\u00fcr ihre kleinen Pf\u00f6tchen hatte aber f\u00fcr den Verk\u00e4ufer den Vorteil das die Exkremente da direkt durchfielen und er einfach nur die Schale darunter reinigen musste.<\/p>\n<p>Ich sag aber nicht nur \u201enormale\u201c Hauskatzen sondern auch Rassekatzen wie Exotic Shorthair, Folds und BKHs. \u00dcber den Pflegezustand der Tiere will ich mich erst gar nicht \u00e4u\u00dfern und eigentlich war es traurig anzusehen wie diese Tiere dort ihr Dasein fristeten.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Heimtiere_und_ihre_Haltung_in_Shanghai\"><\/span>Heimtiere und ihre Haltung in Shanghai<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aber auch hier in Shanghai f\u00e4ngt allm\u00e4hlich ein Umdenken in Bezug auf Heimtierhaltung an und man sieht enorme Unterschiede zwischen den verschiedenen Sozialschichten in Shanghai.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22604 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-05.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Heimtiermarkt\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-05.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-05.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-05.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>W\u00e4hrend der \u00e4rmere Teil der Bev\u00f6lkerung eher ignorant den Haustieren gegen\u00fcber steht und sie f\u00fcr sie nur \u201eMittel zum Zweck sind\u201c wie z.B. M\u00e4usej\u00e4ger etc. ist bei der Mittelschicht ein Haustier schon vergleichbar wie bei uns in Deutschland. Es wird gehegt und gepflegt.<\/p>\n<p>Viele Ladenbesitzer haben Katzen in einem super gepflegten Zustand und w\u00e4hrend nebenan ein kleines K\u00e4tzchen im Laden in einem K\u00e4fig rumturnt und darauf wartet von einer lieben Person gekauft zu werden, &nbsp;sonnt sich im Schuhladen auf einen Kartonstapel eine Katze gen\u00fcsslich und genie\u00dft ihr umsorgtes Leben.<\/p>\n<p>Aber auch in einem Schmuckladen durfte ich eine wundersch\u00f6ne gepflegte halblanghaarige Sch\u00f6nheit bewundern die gerade sichtlich ihre Streicheleinheiten, die ihr zuteilwurden.<\/p>\n<p>Und der schm\u00e4chtige langbeinige rote Kater im Tierladen mit einem unglaublichen Stolz und Selbstbewusstsein, wusste genau wie er sich perfekt f\u00fcr ein Foto in Szene setzen konnte.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22605 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-00.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Shanghai, Taubertalperser, M\u00e4rkte, Fakemarket\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-00.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-00.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Taubertalperser-Heimtiere-00.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Und dann haben wir da noch die Oberschicht f\u00fcr die Hunde ein Statusobjekt darstellt. Hier werden dann die Hunde entsprechend ausstaffiert, geschm\u00fcckt und naja ich formulier es mal so \u2013 es w\u00e4re toll wenn man in Shanghai in Bezug auf Heimtierhaltung ein Mittelding finden w\u00fcrden und nicht von einem Extrem ins andere fallen w\u00fcrden.<\/p>\n<p>Es gibt im \u00dcbrigen in Shanghai ein \u00fcberaus engagiertes Rescue-Team, das sich um herrenlose, streunende Katzen k\u00fcmmert, kastrieren l\u00e4sst und auch wenn notwendig medizinisch versorgt.<\/p>\n<p>So langsam aber sicher ist der Tierschutz auch in China angekommen, es ist sicher noch ein weiter Weg zur Perfektion aber mal ehrlich davon sind wir hier in Deutschland auch noch weit entfernt.<\/p>\n<p>Hier habe ich noch ein paar Fotos f\u00fcr euch<\/p>\n<p>ngg_shortcode_0_placeholder<script type=\"text\/javascript\">\n    google_ad_client = \"ca-pub-3363977028533397\";\n    google_ad_slot = \"3730385664\";\n    google_ad_width = 728;\n    google_ad_height = 90;\n<\/script><br \/>\n<!-- Taubertal2 --><br \/>\n<script type=\"text\/javascript\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\">\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ihr habt schon das eine oder andere von meiner Shanghai-Reise lesen d\u00fcrfen und heute entf\u00fchr ich euch hier zu diversen<\/p>\n","protected":false},"author":1,"featured_media":40882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1,918,1634,2141],"tags":[1541,3123,1606,888,566,21,1183,468,1540,829,1598],"class_list":["post-22600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-katzen-perserkatzen-taubertalperser","category-lifestyle","category-reisen","category-shanghai","tag-china","tag-haustiere","tag-heimtiere","tag-heimtiermarkt","tag-hunde","tag-katzen","tag-katzenblog","tag-reisen","tag-shanghai","tag-taubertalperser","tag-travel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser<\/title>\n<meta name=\"description\" content=\"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser\" \/>\n<meta property=\"og:description\" content=\"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Taubertalperser\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-22T08:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T16:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afrank\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afrank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/\"},\"author\":{\"name\":\"afrank\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"headline\":\"M\u00e4rkte und Heimtiere in Shanghai \u2013 Taubertalperser\",\"datePublished\":\"2018-04-22T08:00:39+00:00\",\"dateModified\":\"2025-01-29T16:55:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/\"},\"wordCount\":1197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1\",\"keywords\":[\"China\",\"Haustiere\",\"Heimtiere\",\"Heimtiermarkt\",\"Hunde\",\"Katzen\",\"Katzenblog\",\"Reisen\",\"Shanghai\",\"Taubertalperser\",\"Travel\"],\"articleSection\":{\"1\":\"Lifestyle\",\"2\":\"Reisen\",\"3\":\"Shanghai\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/\",\"name\":\"Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1\",\"datePublished\":\"2018-04-22T08:00:39+00:00\",\"dateModified\":\"2025-01-29T16:55:34+00:00\",\"description\":\"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1\",\"width\":800,\"height\":300,\"caption\":\"Shanghai, Taubertalperser, Travel, Reisen,\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte und Heimtiere in Shanghai \u2013 Taubertalperser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\",\"name\":\"Die Taubertalperser\",\"description\":\"Alles \u00fcber und f\u00fcr Katzen \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\",\"name\":\"afrank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"width\":653,\"height\":800,\"caption\":\"afrank\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser","description":"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/","og_locale":"de_DE","og_type":"article","og_title":"Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser","og_description":"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere","og_url":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/","og_site_name":"Die Taubertalperser","article_published_time":"2018-04-22T08:00:39+00:00","article_modified_time":"2025-01-29T16:55:34+00:00","og_image":[{"width":800,"height":300,"url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg","type":"image\/jpeg"}],"author":"afrank","twitter_misc":{"Verfasst von":"afrank","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#article","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/"},"author":{"name":"afrank","@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"headline":"M\u00e4rkte und Heimtiere in Shanghai \u2013 Taubertalperser","datePublished":"2018-04-22T08:00:39+00:00","dateModified":"2025-01-29T16:55:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/"},"wordCount":1197,"commentCount":0,"publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1","keywords":["China","Haustiere","Heimtiere","Heimtiermarkt","Hunde","Katzen","Katzenblog","Reisen","Shanghai","Taubertalperser","Travel"],"articleSection":{"1":"Lifestyle","2":"Reisen","3":"Shanghai"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/","url":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/","name":"Shanghai (4) - M\u00e4rkte und Heimtiere in Shanghai - Taubertalperser","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#primaryimage"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1","datePublished":"2018-04-22T08:00:39+00:00","dateModified":"2025-01-29T16:55:34+00:00","description":"Heute lest ihr einen weiteren Teil von meinen Shanghai-Abenteuer. Dieses Mal hat es mich auf diverse M\u00e4rkte gezogen unter anderem auch einen Markt f\u00fcr Heimtiere","breadcrumb":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1","width":800,"height":300,"caption":"Shanghai, Taubertalperser, Travel, Reisen,"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vom-taubertal.de\/blog\/shanghai-4-maerkte-und-heimtiere-in-shanghai-taubertalperser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vom-taubertal.de\/blog\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte und Heimtiere in Shanghai \u2013 Taubertalperser"}]},{"@type":"WebSite","@id":"https:\/\/www.vom-taubertal.de\/blog\/#website","url":"https:\/\/www.vom-taubertal.de\/blog\/","name":"Die Taubertalperser","description":"Alles \u00fcber und f\u00fcr Katzen ","publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vom-taubertal.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049","name":"afrank","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","contentUrl":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","width":653,"height":800,"caption":"afrank"},"logo":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg"}}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/04\/Shanghai-Heimtiere.jpg?fit=800%2C300&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/22600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/comments?post=22600"}],"version-history":[{"count":6,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/22600\/revisions"}],"predecessor-version":[{"id":28612,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/22600\/revisions\/28612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media\/40882"}],"wp:attachment":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media?parent=22600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/categories?post=22600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/tags?post=22600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}