{"id":29676,"date":"2020-03-20T13:21:07","date_gmt":"2020-03-20T11:21:07","guid":{"rendered":"https:\/\/www.vom-taubertal.de\/blog\/?p=29676"},"modified":"2020-06-26T13:12:06","modified_gmt":"2020-06-26T11:12:06","slug":"katzenausstellungen-zwischen-glanz-und-glamour-4","status":"publish","type":"post","link":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/","title":{"rendered":"Wenn kleine Zwetschken nach Pfirsich duften"},"content":{"rendered":"<p>Ich war nun mit meinen Katzen schon mehrmals auf diversen Katzenausstellungen und mit der Anzahl der selbigen wuchs auch mein Inhalt meines Ausstellungskoffers.<\/p>\n<p><!--more--><\/p>\n<p>Eine jede Ausstellung f\u00fcr sich brachte neues Wissen, neue Kontakte, neue Erfahrungen mit sich die man versuchte entsprechend umzusetzen und auch zu nutzen.<\/p>\n<p>Mittlerweile war Dividi nicht nur mehrfach ausgezeichnet worden, sondern auch stolzer Vater entz\u00fcckender kleiner Flauscheb\u00e4llchen. Eines s\u00fc\u00dfer wie das andere und eine davon sollte meine Zucht erweitern \/ vergr\u00f6\u00dfern.<\/p>\n<p>Angel vom Taubertal, die es laut Tierarzt eigentlich nicht geben sollte da man auf dem R\u00f6ntgenbild nur zwei Kitten gesehen hatte, sie aber meinte<\/p>\n<p>\u201eHey, ich bin auch da\u201c.<\/p>\n<p>Angel die, von uns aufgrund ihrer Ambition einfach vom Sofa nur runterzuplumpsen wie eine reife Zwetschke, liebevoll so genannt wurde \u2013 Zwetschke (ich bestehe hier im \u00fcbrigen auf die \u00f6sterreichische Schreibweise)<\/p>\n<p>Ein Name den sie sich erworben und verdient hat, ein Name der sie neben vielen anderen niemals wieder loslassen sollte.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#Zwetschkes_erste_Ausstellung\" >Zwetschke\u2019s erste Ausstellung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#Wenn_kleine_Zwetschken_nach_Pfirsich_duften\" >Wenn kleine Zwetschken nach Pfirsich duften!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#Mit_Katzen_Abends_im_Hotel\" >Mit Katzen Abends im Hotel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#Hier_findet_ihr_weitere_Ausstellungs-Abenteuer\" >Hier findet ihr weitere Ausstellungs-Abenteuer :-)<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Zwetschkes_erste_Ausstellung\"><\/span>Zwetschke\u2019s erste Ausstellung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Man ist nat\u00fcrlich super stolz auf seinen ersten eigenen Nachwuchs. Wie sollte es auch anders sein. Die ersten eignen Kitten, selber aufgezogen, liebevoll umsorgt \u2013 da will man nat\u00fcrlich auch wissen wie andere diese Kitten sehen. Selber ist man ja absolut voreingenommen, die eigenen Katzen sind IMMER die sch\u00f6nsten. Ehrlich, ist so :-)<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29678\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/Katzenausstellung-Zwetschke2-Taubertalperser.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Zwetschke, Katze auf Tisch\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/Katzenausstellung-Zwetschke2-Taubertalperser.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/Katzenausstellung-Zwetschke2-Taubertalperser.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/Katzenausstellung-Zwetschke2-Taubertalperser.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Und nachdem man fr\u00fch genug anfangen sollte mit Ausstellungen damit sich die Katzen auch daran gew\u00f6hnen ging es nach Stuttgart mit meinem A-Wurf zu Animal.<\/p>\n<p>Ja was soll ich gro\u00dfartig sagen, das Foto scheint B\u00e4nde zu sprechen \u2013 ruhig um nicht schon zu sagen gelangweilt hat Zwetschke das Procedere der Begutachtung durch die Richter \u00fcber sich ergehen lassen.<\/p>\n<p>Ja sie hat durchaus positive Bewertungen erhalten was der Beginn einer entsprechenden Ausstellungskarriere war.<\/p>\n<p>Zwetschke, mein s\u00fc\u00dfes kleines Fusselchen mit dem Aussehen einer \u00e4lteren Wollmaus die den Weg unterm Schrank hervorgefunden hat.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Wenn_kleine_Zwetschken_nach_Pfirsich_duften\"><\/span>Wenn kleine Zwetschken nach Pfirsich duften!<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Aber auch kleine Zwetschken werden gro\u00df und sie hat sich zu einem absolut bezaubernden K\u00e4tzchen entwickelt mit einem ausgesprochen liebreizenden Charakter und Verhalten.<br \/>\nJeden Tag wenn ich von der Arbeit heimkam sprang sie mir, mit den ganzen K\u00f6rper wackelnd, freudig entgegen. Wenn man sie ansprach oder sie der Meinung war, sie h\u00e4tte etwas ganz Tolles gemacht (auch wenn sie gerade einen Porzellan\u00fcbertopf gekillt hatte) sa\u00df sie da mit stolzgeschwellter Brust und blickte einen mit gro\u00dfen Augen.<\/p>\n<p style=\"text-align: center;\">\u201eGuck mal Mami, bin ich nicht toll?\u201c<\/p>\n<p style=\"text-align: center;\">\u201eJa, biste meine Kleine\u201c :-)<\/p>\n<p>Es stand wieder einmal ein Ausstellungstermin vor der T\u00fcr und ich steckte viel M\u00fche und Zeit in ihre Fellpflege, regelm\u00e4\u00dfiges baden und f\u00f6hnen sind hier definitiv das A und O.<\/p>\n<p>Aber mein Aufwand sollte sich lohnen Zwetschke sah aus wie eine sch\u00f6ne, gro\u00dfe fluffige Wolke \u2013 genauso wie man es mir gesagt hatte.<\/p>\n<p>Ich war stolz auf sie, meine Zwetschke, mein Baby so bezaubernd sch\u00f6n.<\/p>\n<p>Der erste Ausstellungstag ging auch dementsprechend erfolgreich von statten und die Richter waren voll des Lobes f\u00fcr ihr tolles Fell und die tolle Pflege.<\/p>\n<p>Ach meine kleine, geliebte Zwetschke \u2013 so souver\u00e4n bist du vor den Richtern gesessen, w\u00e4hrend ich danebenstand und vor lauter Stolz fast geplatzt w\u00e4re.<\/p>\n<h3><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29679\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-12.jpg?resize=800%2C536&#038;quality=100&#038;ssl=1\" alt=\"Zwetschke, Katzenausstellung\" width=\"800\" height=\"536\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-12.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-12.jpg?resize=300%2C201&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-12.jpg?resize=768%2C515&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/h3>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?o=3&amp;p=48&amp;l=ez&amp;f=ifr&amp;linkID=7ca51743983b670321939382d4b5288a&amp;t=crazcat-21&amp;tracking_id=crazcat-21\" marginwidth=\"0\" scrolling=\"no\" width=\"728\" height=\"90\" frameborder=\"0\"><\/iframe><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Mit_Katzen_Abends_im_Hotel\"><\/span>Mit Katzen Abends im Hotel<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nach dem Ausstellungstag ging es dann ins Hotel wo nicht nur ausgiebig gespielt, sondern auch entsprechend gekuschelt wurde.<\/p>\n<p>Nur dann, am n\u00e4chsten Tag als ich nach dem Fr\u00fchst\u00fcck ins Zimmer kam war ich nahe eines Herzinfarktes.<\/p>\n<p>Zwetschke kam mir in ihrer unnachahmlichen Art entgegengesprungen, mit stolzer Brust als wollte sie mir wieder sagen<\/p>\n<p style=\"text-align: center;\">&nbsp;\u201eGuck mal Mami, was ich gemacht habe\u201c,<\/p>\n<p>nur dieses Mal konnte ich nicht lachen. In ihrem wundersch\u00f6nen Brustfell, dass ich so toll hinbekommen hatte hing ihre Hinterlassenschaft und leuchtete mir in wundervollen Braun entgegen.<\/p>\n<p style=\"text-align: center;\">\u201eZwetschke, NEIN!!!! Wie hast du denn das hinbekommen?\u201c<\/p>\n<p>Verzweiflung machte sich in mir breit, Shampoo hatte ich ja mit aber der Hotelf\u00f6hn war nun nicht wirklich etwas. Bei einer Z\u00fcchterkollegin organisierte ich mir einen entsprechenden Haarf\u00f6n und versuchte das Malheur zu beseitigen und zu retten, was zu retten ist.<\/p>\n<p>Shampoo, Puder \u2013 alles Greifbare kam zum Einsatz und es gelang mir auch das Fell halbwegs wieder in Ordnung zu bringen. Nur es war noch so ein leichter Dufthauch von \u201eEau de G\u00fcll\u201c in der Luft.<\/p>\n<p>Wusstet ihr das es Katzenparfum gibt?<\/p>\n<p>Nein?<\/p>\n<p>Nun ich bis zu dem Tag auch nicht aber eine hilfreiche Fee hat mir dies bei der Ausstellung organisiert und so sa\u00df dann eine nach Pfirsich duftende Zwetschke vor dem Richter und sah ihn mit gro\u00dfen Kulleraugen an, getreu ihrem Motto<\/p>\n<p style=\"text-align: center;\">&#8222;Bin ich nicht toll?&#8220;<\/p>\n<p>Danke meine kleine Zwetschke, f\u00fcr diese unvergesslichen Momente :-)<\/p>\n<p>Seitdem hatte ich dann IMMER einen entsprechenden F\u00f6hn dabei, sowie Katzenparfum mit Pfirsich-Note das im \u00dcbrigen nie wieder zum Einsatz kam ;-)<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29680\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-03pg.jpg?resize=600%2C400&#038;quality=100&#038;ssl=1\" alt=\"Zwetschke\" width=\"600\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-03pg.jpg?w=600&amp;quality=100&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/03\/02-Taubertalperser-Katzenausstellung-03pg.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-3363977028533397\" data-ad-slot=\"1497449773\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Hier_findet_ihr_weitere_Ausstellungs-Abenteuer\"><\/span>Hier findet ihr weitere Ausstellungs-Abenteuer :-)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><em><strong><a href=\"https:\/\/www.vom-taubertal.de\/blog\/unsere-ersten-katzenausstellung-zwischen-hoffen-und-bangen\/\" target=\"_blank\" rel=\"noopener\">Unsere erste Katzenausstellung<\/a><\/strong><\/em><\/li>\n<li><em><strong><a href=\"https:\/\/www.vom-taubertal.de\/blog\/abtenteuer-katzenausstellung-privatpension-niemals-wieder\/\" target=\"_blank\" rel=\"noopener\">Abenteuer Privatpension &#8211; Niemals wieder<\/a><\/strong><\/em><\/li>\n<li><em><strong><a href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour\/\" target=\"_blank\" rel=\"noopener\">Wenn gro\u00dfe Katzen denken sie w\u00e4ren klein<\/a><\/strong><\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ich war nun mit meinen Katzen schon mehrmals auf diversen Katzenausstellungen und mit der Anzahl der selbigen wuchs auch mein<\/p>\n","protected":false},"author":1,"featured_media":29378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1,6],"tags":[1426,2424,2397,827,1183,829,1964],"class_list":["post-29676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-katzen-perserkatzen-taubertalperser","category-katzenausstellungen-perserkatzen-taubertalperser","tag-abenteuer","tag-erinnerung","tag-erlebnisse","tag-katzenausstellungen-perserkatzen-taubertalperser","tag-katzenblog","tag-taubertalperser","tag-zwetschke"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser<\/title>\n<meta name=\"description\" content=\"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser\" \/>\n<meta property=\"og:description\" content=\"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Taubertalperser\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T11:21:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-26T11:12:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afrank\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afrank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/\"},\"author\":{\"name\":\"afrank\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"headline\":\"Wenn kleine Zwetschken nach Pfirsich duften\",\"datePublished\":\"2020-03-20T11:21:07+00:00\",\"dateModified\":\"2020-06-26T11:12:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/\"},\"wordCount\":833,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1\",\"keywords\":[\"Abenteuer\",\"Erinnerung\",\"Erlebnisse\",\"Katzenausstellung\",\"Katzenblog\",\"Taubertalperser\",\"Zwetschke\"],\"articleSection\":{\"1\":\"Katzenausstellung\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/\",\"name\":\"Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1\",\"datePublished\":\"2020-03-20T11:21:07+00:00\",\"dateModified\":\"2020-06-26T11:12:06+00:00\",\"description\":\"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1\",\"width\":800,\"height\":533,\"caption\":\"Katzenausstellungen, Erfahrungen, Glanz und Glamour, Taubertalperser, Katzenblog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/katzenausstellungen-zwischen-glanz-und-glamour-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wenn kleine Zwetschken nach Pfirsich duften\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\",\"name\":\"Die Taubertalperser\",\"description\":\"Alles \u00fcber und f\u00fcr Katzen \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\",\"name\":\"afrank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"width\":653,\"height\":800,\"caption\":\"afrank\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser","description":"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/","og_locale":"de_DE","og_type":"article","og_title":"Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser","og_description":"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke","og_url":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/","og_site_name":"Die Taubertalperser","article_published_time":"2020-03-20T11:21:07+00:00","article_modified_time":"2020-06-26T11:12:06+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg","type":"image\/jpeg"}],"author":"afrank","twitter_misc":{"Verfasst von":"afrank","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#article","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/"},"author":{"name":"afrank","@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"headline":"Wenn kleine Zwetschken nach Pfirsich duften","datePublished":"2020-03-20T11:21:07+00:00","dateModified":"2020-06-26T11:12:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/"},"wordCount":833,"commentCount":2,"publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1","keywords":["Abenteuer","Erinnerung","Erlebnisse","Katzenausstellung","Katzenblog","Taubertalperser","Zwetschke"],"articleSection":{"1":"Katzenausstellung"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/","url":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/","name":"Wenn kleine Zwetschken nach Pfirsich duften - Taubertalperser","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#primaryimage"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1","datePublished":"2020-03-20T11:21:07+00:00","dateModified":"2020-06-26T11:12:06+00:00","description":"Wenn man so in Erinnerung schwelgt, f\u00e4llt einem die eine oder andere Begebenheit ein, die man so erlebt hat bei Katzenausstellungen wie mit Zwetschke","breadcrumb":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1","width":800,"height":533,"caption":"Katzenausstellungen, Erfahrungen, Glanz und Glamour, Taubertalperser, Katzenblog"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vom-taubertal.de\/blog\/katzenausstellungen-zwischen-glanz-und-glamour-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vom-taubertal.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Wenn kleine Zwetschken nach Pfirsich duften"}]},{"@type":"WebSite","@id":"https:\/\/www.vom-taubertal.de\/blog\/#website","url":"https:\/\/www.vom-taubertal.de\/blog\/","name":"Die Taubertalperser","description":"Alles \u00fcber und f\u00fcr Katzen ","publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vom-taubertal.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049","name":"afrank","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","contentUrl":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","width":653,"height":800,"caption":"afrank"},"logo":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg"}}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2020\/02\/glanz-und-glamour-Katzenausstellungen-Taubertalperser.jpg?fit=800%2C533&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/29676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/comments?post=29676"}],"version-history":[{"count":7,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/29676\/revisions"}],"predecessor-version":[{"id":35099,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/29676\/revisions\/35099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media\/29378"}],"wp:attachment":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media?parent=29676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/categories?post=29676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/tags?post=29676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}