{"id":33012,"date":"2022-08-05T13:06:09","date_gmt":"2022-08-05T11:06:09","guid":{"rendered":"https:\/\/www.vom-taubertal.de\/blog\/?p=33012"},"modified":"2024-10-16T16:29:19","modified_gmt":"2024-10-16T14:29:19","slug":"produktvorstellung-der-taubertalperser-catrub-one","status":"publish","type":"post","link":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/","title":{"rendered":"Produktvorstellung der Taubertalperser &#8211;  Catrub One"},"content":{"rendered":"<p>Als wir bei der Interzoo unterwegs waren stolperten wir auch \u00fcber das Unternehmen Catrub.&nbsp;<br \/>\nAls ich mich dem Stand n\u00e4herte war man gerade im Aufbau eines Catrub One und man wollte eigentlich das nicht weiter demonstrieren, aber als ich dann anmerkte<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\">\u201eMich interessiert das nun auch sehr stark\u201c<\/p>\n<p>wurde es bis ins kleinste Detail demonstriert.<\/p>\n<p>Ihr wisst ich bin in manchen Dingen echt typisch Frau, mit den Absch\u00e4tzen von Gr\u00f6\u00dfe und so habe ich es nicht so wirklich (habe ich euch eigentlich den Teichk\u00e4scher gezeigt, den ich mir zulegte, um Bl\u00e4tter aus unseren Miniteich zu fischen? Laut meinem Mann ist der hochseetauglich f\u00fcr gro\u00dfe, sehr sehr gro\u00dfe Fische-Thunfische oder gr\u00f6\u00dfer)<\/p>\n<p>Vor Ort konnte ich mich schon einmal \u00fcber die leichte Aufbauweise \u00fcberzeugen und auch die Qualit\u00e4t war ausgesprochen interessant. Machte auf den ersten Blick alles einen hochwertigen und vor allem stabilen Eindruck.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-00.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39812 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-00.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub Karton C.O. Tigerkatze, Taubertalperser\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-00.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-00.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-00.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Nur wie sieht es aus im Praxistest? Passt da Dividi hinein? W\u00fcrden unsere Katzen dieses Teil akzeptieren?<\/p>\n<p>Ich habe in all den Jahren so viel Schund gekauft, das auf den ersten Blick super toll aussah. Im Nachgang sich aber als totaler Flop erwies.<\/p>\n<p>Auch einer der Gr\u00fcnde, warum ich euch hier das eine oder andere Produkt zeige. Ihr m\u00fcsst nicht den gleichen Fehler wie ich begehen und euer sauer verdientes Geld im wahrsten Sinne des Wortes \u201everbrennen\u201c.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Das_sagt_der_Hersteller_zu_Catrub_One\" >Das sagt der Hersteller zu Catrub One<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Das_sagen_die_Taubertalperser_und_ihr_Personal_zu_Catrub_One\" >Das sagen die Taubertalperser und ihr Personal zu Catrub One<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Einfacher_Aufbau\" >Einfacher Aufbau<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Einfache_Reinigung\" >Einfache Reinigung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Langlebig_Nachhaltig\" >Langlebig &amp; Nachhaltig<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Catrube_one_%E2%80%93_ALL-IN-ONE\" >Catrube one &#8211; ALL-IN-ONE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#Die_Groesse_%E2%80%93_laut_Hersteller_die_perfekte_Groesse\" >Die Gr\u00f6\u00dfe \u2013 laut Hersteller die perfekte Gr\u00f6\u00dfe<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Das_sagt_der_Hersteller_zu_Catrub_One\"><\/span>Das sagt der Hersteller zu Catrub One<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Catrub ONE ist das erste modulare multifunktionale Katzenm\u00f6bel, welches alle wichtigen Funktionen in Einklang mit einem modernen Design bringt.<\/p>\n<p>Ausgezeichnet mit dem <strong>German Design <\/strong>und dem <strong>IF Design Award<\/strong>.<\/p>\n<p>H\u00f6he: 93 cm<br \/>\nBreite: 47 cm<br \/>\nTiefe: 35 cm<\/p>\n<p><strong>Gewicht:&nbsp;<\/strong>ca. 8,5 kg<\/p>\n<p><strong>Material:<\/strong><\/p>\n<p>Geh\u00e4use: HIPS (High Impact Polystyrene) in Wei\u00df oder Anthrazit.<br \/>\nSisal: Natursisal in Teppichqualit\u00e4t.<\/p>\n<p>Kissen: Kissen inklusive feuchtigkeitsabweisendes Inlett bestehend aus 95% Polyester und 5% Polypropylen.<\/p>\n<figure id=\"attachment_33018\" aria-describedby=\"caption-attachment-33018\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/07\/Catrub-Aufbau2.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33018\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/07\/Catrub-Aufbau2.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub Khalessi, Perserkatze, Produkttest\" width=\"800\" height=\"533\"><\/a><figcaption id=\"caption-attachment-33018\" class=\"wp-caption-text\">Geht das nicht schneller?<\/figcaption><\/figure>\n<p><strong>Montage:&nbsp;<\/strong>F\u00fcr den Aufbau musst Du lediglich die Holzf\u00fc\u00dfe selbst montieren. Anleitung, Werkzeug und Schrauben f\u00fcr die schnelle und einfache Montage sind im Lieferumfang enthalten.<\/p>\n<p>Hinweis: Bei&nbsp;Sisal und Holzf\u00fc\u00dfen&nbsp;handelt es sich um Naturprodukte, leichte Farbunterschiede sind m\u00f6glich.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Das_sagen_die_Taubertalperser_und_ihr_Personal_zu_Catrub_One\"><\/span>Das sagen die Taubertalperser und ihr Personal zu Catrub One<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ich muss gestehen, ich war skeptisch \u2013 sehr skeptisch. Auf Bildern so im Internet sieht immer alles gro\u00dfartig und super aus. Ist allgemein bekannt und dann h\u00e4tten wir sicher noch Photoshop-Klaus, der das eine oder andere auch \u201esch\u00f6nt\u201c, um es gut darzustellen.<br \/>\nIst auch legitim sorgt aber nicht daf\u00fcr, dass meine Skepsis dem Teil gegen\u00fcber sich zerstreut.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-06.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39814 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-06.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub, Produkttest, Aufbauanleitung, Werkzeug\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-06.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-06.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-06.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Wer aber f\u00fcr ein Katzenm\u00f6bel 200 Euro ausgibt will es einfach genauer wissen. So auch ich und war echt froh als ich den Hersteller bei der Interzoo getroffen habe.<\/p>\n<p>Es dauerte dann noch ein paar Tage, bis ich unseren Catrub hier aufbauen konnte. Aber nun war es nun soweit \u2013 frisch ans Werk und testen &#x1f60a;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Einfacher_Aufbau\"><\/span>Einfacher Aufbau<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wooow, der Aufbau ist simpel. Also richtig einfach und das bekommt sogar jemand hin, der die sprichw\u00f6rtlichen zwei linken H\u00e4nde hat.<\/p>\n<p>Man hat hier verschiedene M\u00f6glichkeiten \u2013 mit Beinen oder ohne. Nur ein Modul oder alles zusammen.<\/p>\n<p>Man kann hier tats\u00e4chlich nichts falsch machen und die Aufbauanleitung, ehrlich die ist nur Makulatur \u2013 eigentlich nicht zwingend notwendig, weil vieles selbsterkl\u00e4rend ist.<\/p>\n<p>Besonders erw\u00e4hnenswert sind die unterschiedlich gro\u00dfen L\u00f6cher bei den Holzbeinen. Das muss so sein, erkennt man dadurch sofort, wie man sie am Unterteil anzuschrauben hat.<br \/>\nWer keine Holzbeine mag kann sie weglassen und hat dann entsprechende Gummistopper am Boden. Mein Mann war da echt begeistert als er das gesehen hat.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-04.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39813 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-04.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub Holzbein Aufbau\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-04.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-04.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-04.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>Wir haben uns f\u00fcr die Variante mit den Holzbeinen entschieden und das macht echt einen schicken Eindruck.<\/p>\n<p>Das mitgelieferte Aufbauwerkzeug rundet das ausgezeichnete durchdachte Gesamtbild nur ab.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Einfache_Reinigung\"><\/span>Einfache Reinigung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Katzen sind eigentlich super reinliche Tiere. Wissen hin- und wieder nur unsere Katzen nicht so ganz und da kann schon mal der eine oder andere \u201eUnfall\u201c passieren. Oder sie haben wieder die Idee ihre Haare irgendwie dort auszukotzen wo vorzugsweise keine Fliesen, sondern Teppich oder \u00e4hnliches liegt.<\/p>\n<p>Gut, dass man hier bei diesem Katzenm\u00f6belteil echt ein St\u00fcck weitergedacht hat. Ein jedes Teil ist superleicht zu s\u00e4ubern.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-05.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39815 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-05.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub Khalessi\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-05.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-05.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-05.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>Aber es muss jetzt nicht mal sein, dass Katze \u201erumgesaut\u201c hat. Ich brauche nur an die Giardieninfektion von unserem Neuzugang C.O. aka Brummhummelchen denken.<\/p>\n<p>Ihr Lieblingsteil von <strong>Canadian Cat Company<\/strong> musste ich notgedrungen entsorgen. Das h\u00e4tte ich nie wieder hygienisch sauber bekommen ohne das eine Re-Infektion stattgefunden h\u00e4tte. Mir hat bei der Entsorgung zwar das Herz geblutet, zumal es nicht gerade preiswert war, aber wat mutt dat mutt oder so \u00e4hnlich.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Langlebig_Nachhaltig\"><\/span>Langlebig &amp; Nachhaltig<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Dieses M\u00f6belteil ist aus recht robustem Material und auch die Verarbeitung ist ausgesprochen gut. Da ist nichts Scharfkantiges an denen Katze sich verletzten k\u00f6nnte.<\/p>\n<p>Auch superpraktisch, dass s\u00e4mtliche Verschlei\u00dfteile separat nachkaufbar sind. Ausgesprochen gut durchdachtes Interieur f\u00fcr Katzen, muss man echt schon mal lobend erw\u00e4hnen.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-07.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39816 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-07.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub, Tigerkatze\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-07.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-07.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-07.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Catrube_one_%E2%80%93_ALL-IN-ONE\"><\/span>Catrube one &#8211; ALL-IN-ONE<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Der Hersteller gibt als Ziel an, dass er ein M\u00f6belteil schaffen wollte, das alle wichtigen Funktionen vereint.<\/p>\n<p>Das ist ihm Gro\u00dfteils auch gelungen, nur ersetzt es tats\u00e4chlich keinen Kratzbaum an denen Katze sich in allen Formen ihrer Krallenpflege widmen kann.<\/p>\n<p>Aber im Gro\u00dfen und Ganzen ist dieses M\u00f6belteil f\u00fcr alle Katzen geeignet. Und auch ich war positiv \u00fcberrascht, wie harmonisch es sich in unser Wohnzimmer einf\u00fcgt.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Die_Groesse_%E2%80%93_laut_Hersteller_die_perfekte_Groesse\"><\/span>Die Gr\u00f6\u00dfe \u2013 laut Hersteller die perfekte Gr\u00f6\u00dfe<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u00c4hm ja, ich h\u00e4tte es nicht f\u00fcr m\u00f6glich gehalten und nicht geglaubt, wenn ich es nicht hier selbst getestet und mit eigenen Augen gesehen h\u00e4tte.<\/p>\n<p>Alle Katzen bei uns finden den <strong>Catrube One<\/strong> genial. Egal welcher Gr\u00f6\u00dfe oder Alter.&nbsp; Ich bin \u00fcberrascht und fasziniert zugleich.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-08.jpg?quality=100&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39817 size-full\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-08.jpg?resize=800%2C533&#038;quality=100&#038;ssl=1\" alt=\"Catrub, Tigerkatze, Brummhummelchen\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-08.jpg?w=800&amp;quality=100&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-08.jpg?resize=300%2C200&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-08.jpg?resize=768%2C512&amp;quality=100&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>Was wir bei uns nicht im Einsatz haben ist der Schrubber f\u00fcrs Fell aus Standgr\u00fcnden, ansonsten sind alle schon mehr oder weniger drinnen gelegen, haben darin gespielt oder ihren Platz mit den Pfoten verteidigt &#x1f60a;<\/p>\n<p>Und wisst ihr was das Geniale ist? Wenn wir uns daran satt gesehen haben, wird er sch\u00f6n zerlegt und auf den Dachboden gestellt, um zu einem anderen Zeitpunkt wieder zum Einsatz zu kommen &#x1f60a;<\/p>\n<p>Und sollten wir wider Erwarten einmal keine Katzen mehr haben findet das tolle St\u00fcck seinen Weg ins Tierheim, da es so robust und langlebig ist \u2013 das \u00fcberlebt viele Katzen &#x1f60a;<\/p>\n<p>Von uns gibt es hier an dieser Stelle eine klare und eindeutige Kaufempfehlung.<\/p>\n<p>Erh\u00e4ltlich ist das gute St\u00fcck direkt auf der <em><strong><a href=\"https:\/\/catrub.com\/\" target=\"_blank\" rel=\"noopener\">Webseite des Herstellers<\/a><\/strong><\/em> und ihr habt dort wie Wahl zwischen zwei Farben \u2013 entweder im dezenten Anthrazit oder im stylischen Wei\u00df.<\/p>\n<p>Nur der Ordnung halber, dieses Produkt wurde uns von Catrub kostenlos zur Verf\u00fcgung gestellt was aber weder meine noch die Meinung der Katzen beeinflusste.<\/p>\n<hr>\n<p>Hat dir dieser Beitrag gefallen und du m\u00f6chtest auch in der Zukunft keine tollen Tipps zur Katzenhaltung oder interessante Produktempfehlungen verpassen?<br \/>\nAbonniere einfach unseren Blog und erhalte die neuesten Beitr\u00e4ge einfach direkt in den Mailfach.<\/p>\n<p>Gerne darfst du auch unsere Beitr\u00e4ge mit anderen Katzenliebhabern teilen.<\/p>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3363977028533397\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-3363977028533397\" data-ad-slot=\"1497449773\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><br \/>\n<a href=\"https:\/\/www.vom-taubertal.de\/blog\/partner-links-was-ist-das\/\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-35175\" src=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/02\/Partnerlinks.png?resize=350%2C99&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"350\" height=\"99\" srcset=\"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/02\/Partnerlinks.png?w=350&amp;quality=100&amp;ssl=1 350w, https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2018\/02\/Partnerlinks.png?resize=300%2C85&amp;quality=100&amp;ssl=1 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p><!-- START ADVERTISER: Pets Deli DE\/AT from awin.com --><\/p>\n<p><a href=\"https:\/\/www.awin1.com\/cread.php?s=3056781&amp;v=22950&amp;q=415746&amp;r=557159\" rel=\"sponsored\"><br \/>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.awin1.com\/cshow.php?s=3056781&amp;v=22950&amp;q=415746&amp;r=557159\" border=\"0\"><br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als wir bei der Interzoo unterwegs waren stolperten wir auch \u00fcber das Unternehmen Catrub.&nbsp; Als ich mich dem Stand n\u00e4herte<\/p>\n","protected":false},"author":1,"featured_media":39810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1190,1,29,1162],"tags":[2761,21,1183,2213,2762,843,828,8,1886],"class_list":["post-33012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alles-ueber-katzen","category-allgemein-katzen-perserkatzen-taubertalperser","category-produktvorstellung-taubertalperser-perserkatzen","category-testreihen","tag-catrub","tag-katzen","tag-katzenblog","tag-katzeninformationsseite","tag-modulare-multifunktionale-katzenmoebel","tag-produkttest","tag-produktvorstellung-taubertalperser-perserkatzen","tag-rund-um-die-katz","tag-unabhaengiger-katzenblog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produktvorstellung der Taubertalperser - Catrub One<\/title>\n<meta name=\"description\" content=\"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produktvorstellung der Taubertalperser - Catrub One\" \/>\n<meta property=\"og:description\" content=\"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/\" \/>\n<meta property=\"og:site_name\" content=\"Die Taubertalperser\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-05T11:06:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T14:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afrank\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afrank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/\"},\"author\":{\"name\":\"afrank\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"headline\":\"Produktvorstellung der Taubertalperser &#8211; Catrub One\",\"datePublished\":\"2022-08-05T11:06:09+00:00\",\"dateModified\":\"2024-10-16T14:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/\"},\"wordCount\":1208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1\",\"keywords\":[\"Catrub\",\"Katzen\",\"Katzenblog\",\"Katzeninformationsseite\",\"modulare multifunktionale Katzenm\u00f6bel\",\"Produkttest\",\"Produktvorstellung\",\"Rund um die Katz'\",\"unabh\u00e4ngiger Katzenblog\"],\"articleSection\":{\"0\":\"Alles \u00fcber Katzen\",\"2\":\"Produktvorstellung\",\"3\":\"Tests f\u00fcr die Katz'\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/\",\"name\":\"Produktvorstellung der Taubertalperser - Catrub One\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1\",\"datePublished\":\"2022-08-05T11:06:09+00:00\",\"dateModified\":\"2024-10-16T14:29:19+00:00\",\"description\":\"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1\",\"width\":800,\"height\":300,\"caption\":\"Catrub, Taubertalperser, Produkttest, Produktvorstellung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/produktvorstellung-der-taubertalperser-catrub-one\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produktvorstellung der Taubertalperser &#8211; Catrub One\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/\",\"name\":\"Die Taubertalperser\",\"description\":\"Alles \u00fcber und f\u00fcr Katzen \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/#\\\/schema\\\/person\\\/368654e092f5785df440fe834ecc3049\",\"name\":\"afrank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"url\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\",\"width\":653,\"height\":800,\"caption\":\"afrank\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.vom-taubertal.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Andrea_Dividi_02.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produktvorstellung der Taubertalperser - Catrub One","description":"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/","og_locale":"de_DE","og_type":"article","og_title":"Produktvorstellung der Taubertalperser - Catrub One","og_description":"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden","og_url":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/","og_site_name":"Die Taubertalperser","article_published_time":"2022-08-05T11:06:09+00:00","article_modified_time":"2024-10-16T14:29:19+00:00","og_image":[{"width":800,"height":300,"url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg","type":"image\/jpeg"}],"author":"afrank","twitter_misc":{"Verfasst von":"afrank","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#article","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/"},"author":{"name":"afrank","@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"headline":"Produktvorstellung der Taubertalperser &#8211; Catrub One","datePublished":"2022-08-05T11:06:09+00:00","dateModified":"2024-10-16T14:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/"},"wordCount":1208,"commentCount":0,"publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1","keywords":["Catrub","Katzen","Katzenblog","Katzeninformationsseite","modulare multifunktionale Katzenm\u00f6bel","Produkttest","Produktvorstellung","Rund um die Katz'","unabh\u00e4ngiger Katzenblog"],"articleSection":{"0":"Alles \u00fcber Katzen","2":"Produktvorstellung","3":"Tests f\u00fcr die Katz'"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/","url":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/","name":"Produktvorstellung der Taubertalperser - Catrub One","isPartOf":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#primaryimage"},"image":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1","datePublished":"2022-08-05T11:06:09+00:00","dateModified":"2024-10-16T14:29:19+00:00","description":"Catrube das modulare multifunktionale Katzenm\u00f6bel ist bei uns eingezogen und durfte von den Taubertalperserchen und Brummhummel getestet werden","breadcrumb":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1","width":800,"height":300,"caption":"Catrub, Taubertalperser, Produkttest, Produktvorstellung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vom-taubertal.de\/blog\/produktvorstellung-der-taubertalperser-catrub-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vom-taubertal.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Produktvorstellung der Taubertalperser &#8211; Catrub One"}]},{"@type":"WebSite","@id":"https:\/\/www.vom-taubertal.de\/blog\/#website","url":"https:\/\/www.vom-taubertal.de\/blog\/","name":"Die Taubertalperser","description":"Alles \u00fcber und f\u00fcr Katzen ","publisher":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vom-taubertal.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.vom-taubertal.de\/blog\/#\/schema\/person\/368654e092f5785df440fe834ecc3049","name":"afrank","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","url":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","contentUrl":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg","width":653,"height":800,"caption":"afrank"},"logo":{"@id":"https:\/\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2019\/03\/Andrea_Dividi_02.jpg"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vom-taubertal.de\/blog\/wp-content\/uploads\/2022\/08\/Catrub-Titelbild.jpg?fit=800%2C300&quality=100&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/33012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/comments?post=33012"}],"version-history":[{"count":7,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/33012\/revisions"}],"predecessor-version":[{"id":39818,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/posts\/33012\/revisions\/39818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media\/39810"}],"wp:attachment":[{"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/media?parent=33012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/categories?post=33012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vom-taubertal.de\/blog\/wp-json\/wp\/v2\/tags?post=33012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}